{"id":7652,"date":"2022-07-11T09:40:42","date_gmt":"2022-07-11T09:40:42","guid":{"rendered":"https:\/\/turkeyistanbulmedical.com\/?p=7652"},"modified":"2022-10-01T12:50:58","modified_gmt":"2022-10-01T12:50:58","slug":"quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires","status":"publish","type":"post","link":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/","title":{"rendered":"Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires"},"content":{"rendered":"<h2><strong>Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? <\/strong><\/h2>\n<h2><strong>(\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires)<\/strong><\/h2>\n<h3><strong>Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ?<\/strong><\/h3>\n<p>Le <a href=\"https:\/\/www.turkeyistanbulmedical.com\/fr\/\">syndrome de congestion\u00a0 veineuse pelvienne<\/a> est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieure du tronc. Cette maladie, \u00e9galement traduite par syndrome d&#8217;obstruction pelvienne, est connue sous le nom de varices ut\u00e9rines.<\/p>\n<p>Elle est caus\u00e9e par l&#8217;occlusion des vaisseaux sanguins dans le bassin et l&#8217;accumulation de sang en exc\u00e8s dans cette zone.<\/p>\n<p>Le bassin est une structure situ\u00e9e dans la partie inf\u00e9rieure du corps. Il est \u00e9troitement li\u00e9 \u00e0 diff\u00e9rents organes et syst\u00e8mes. Il est associ\u00e9 au syst\u00e8me reproducteur, au syst\u00e8me urinaire et au syst\u00e8me digestif. Et il soutient la partie inf\u00e9rieure de notre corps.<\/p>\n<p>Il porte pr\u00e8s de la moiti\u00e9 du poids corporel d&#8217;une personne. Je ne peux pas donner d&#8217;informations pr\u00e9cises sur son incidence dans la communaut\u00e9, mais 1 patient sur 10 qui se plaint de douleurs abdominales \u00e0 long terme est associ\u00e9 \u00e0 une obstruction pelvienne.<\/p>\n<p>Si nous listons d&#8217;autres noms connus :<\/p>\n<ul>\n<li>Syndrome de congestion veineuse pelvienne chronique<\/li>\n<li>Syndrome d&#8217;obstruction veineuse pelvienne chronique<\/li>\n<li>Taylor<\/li>\n<li>Varices de la r\u00e9gion g\u00e9nitale<\/li>\n<li>H\u00e9ritiers ut\u00e9rins<\/li>\n<\/ul>\n<h3><strong>Quelles Sont Les Causes Du Syndrome De Congestion Pelvienne ?<\/strong><\/h3>\n<p>La cause la plus fondamentale du syndrome d&#8217;obstruction pelvienne est la pr\u00e9sence d&#8217;une obstruction et d&#8217;une dilatation des veines pelviennes (veine r\u00e9nale r\u00e9troaortique droite et gauche).<\/p>\n<p>D&#8217;autres situations sont :<\/p>\n<ul>\n<li>Avoir une histoire de deux naissances ou plus<\/li>\n<li>Augmentation anormale des taux d&#8217;hormones<\/li>\n<li>Pr\u00e9sence d&#8217;occlusion dans les veines des jambes ou ant\u00e9c\u00e9dents de thrombose veineuse profonde<\/li>\n<li>Pr\u00e9sence d&#8217;ovaires polykystiques<\/li>\n<li>D\u00e9s\u00e9quilibres hormonaux et certains dysfonctionnements<\/li>\n<li>Petitesse anatomique cong\u00e9nitale dans la r\u00e9gion du bassin<\/li>\n<li>Expansion des vaisseaux ut\u00e9rins pour une raison quelconque<\/li>\n<\/ul>\n<h3><strong>Qu&#8217;est-Ce Qui Cause La Congestion Pelvienne?<\/strong><\/h3>\n<p>Le &#8220;syndrome de congestion pelvienne&#8221;, connu parmi la population sous le nom d'&#8221;expansion des vaisseaux ut\u00e9rins&#8221;, peut survenir pour de nombreuses raisons diff\u00e9rentes. La majorit\u00e9 des personnes atteintes de ce syndrome se plaignent d&#8217;abord d&#8217;une douleur contondante qui irradie vers l&#8217;aine ou l&#8217;aine et provoque un grand inconfort.<\/p>\n<h3><strong>Quels Sont Les Sympt\u00f4mes Du Syndrome De Congestion Pelvienne ?<\/strong><\/h3>\n<p>En raison des blocages dans la r\u00e9gion pelvienne, comme je l&#8217;ai d\u00e9crit ci-dessus, certains sympt\u00f4mes se manifesteront chez les personnes.<\/p>\n<ul>\n<li>Une douleur lancinante dans la r\u00e9gion du tronc (\u00e9galement connue sous le nom de douleur pelvienne chronique).<\/li>\n<li>Mal au dos<\/li>\n<li>Saignements vaginaux anormaux (les menstruations sont probl\u00e9matiques.)<\/li>\n<li>Fatigue et faiblesse facilement<\/li>\n<li>Vessie irritable<\/li>\n<li>Douleur pendant les rapports sexuels<\/li>\n<li>Des troubles de l&#8217;humeur ou une d\u00e9pression peuvent \u00e9galement survenir.<\/li>\n<\/ul>\n<h3><strong>Quelles Sont Les Complications Du Syndrome De Congestion Pelvienne ?<\/strong><\/h3>\n<p>Un certain nombre de complications peuvent \u00eatre observ\u00e9es chez les patients qui ne sont pas intervenus ou trait\u00e9s en temps opportun.<\/p>\n<p>Ces:<\/p>\n<ul>\n<li>Possibles fractures et luxations osseuses<\/li>\n<li>Occlusions veineuses<\/li>\n<li>Perturbation du syst\u00e8me circulatoire<\/li>\n<li>Douleur intense dans la r\u00e9gion pelvienne qui ne dispara\u00eet pas<\/li>\n<\/ul>\n<p>Le diagnostic du syndrome de congestion pelvienne peut \u00eatre pos\u00e9 facilement avec des m\u00e9thodes d&#8217;imagerie avanc\u00e9es telles que la tomodensitom\u00e9trie, l&#8217;\u00e9chographie et l&#8217;\u00e9chographie transvaginale en plus de l&#8217;examen.<\/p>\n<h3><strong>Facteurs Causant Le Syndrome De Congestion Pelvienne<\/strong><\/h3>\n<p>Le reflux de sang dans les ovaires et les veines pelviennes d\u00fb \u00e0 des valves insuffisantes est le principal probl\u00e8me dans la survenue du syndrome de congestion pelvienne. Cependant, l&#8217;\u00e9mergence de ce syndrome peut \u00e9galement \u00eatre due \u00e0 des conditions anatomiques obstructives et \u00e0 des maladies.<\/p>\n<p>Dans la section suivante, les raisons de l&#8217;insuffisance des valves dans les veines pelviennes et ovariennes sont \u00e9num\u00e9r\u00e9es\u00a0:<\/p>\n<ul>\n<li>Modifications structurelles de la paroi veineuse<\/li>\n<li>Sur-stimulation sur ces veines avec l&#8217;augmentation des \u0153strog\u00e8nes<\/li>\n<li>Changements primaires dans les structures des vannes<\/li>\n<\/ul>\n<p>Un autre facteur qui cause le &#8220;syndrome de congestion pelvienne&#8221; est &#8220;l&#8217;accouchement multiple&#8221;. En raison du fait que les hormones \u0153strog\u00e8nes et progest\u00e9rone ont des effets vasodilatateurs, des &#8220;expansions&#8221;, c&#8217;est-\u00e0-dire des &#8220;varices&#8221;, se produisent dans les veines intra-abdominales et des jambes, \u00e0 la fois pour des raisons hormonales et en raison de la pression du b\u00e9b\u00e9 dans l&#8217;ut\u00e9rus sur les veines de la m\u00e8re pendant le processus de grossesse.<\/p>\n<p>Cette situation survient dans un certain laps de temps et se d\u00e9veloppe g\u00e9n\u00e9ralement en raison de la d\u00e9t\u00e9rioration du &#8220;m\u00e9canisme de la valve veineuse&#8221; dans la veine, c&#8217;est-\u00e0-dire des &#8220;valves&#8221;.<\/p>\n<p>Cependant, la prise de poids pendant la grossesse et les modifications anatomiques des structures pelviennes dues \u00e0 la grossesse affectent directement le flux sanguin veineux dans la r\u00e9gion pelvienne.<\/p>\n<p>En raison de l&#8217;accumulation de sang dans les veines pelviennes et ovariennes, c&#8217;est-\u00e0-dire les veines &#8220;ovariennes&#8221;, le flux sanguin vers les veines saines ralentit et s&#8217;arr\u00eate m\u00eame.<\/p>\n<p>De ce point de vue, la &#8220;douleur pelvienne&#8221; survient g\u00e9n\u00e9ralement \u00e0 la suite de la coagulation du sang (thrombose) dans la veine et de la pression exerc\u00e9e par les veines \u00e9largies sur les nerfs voisins.<\/p>\n<p>Les conditions particuli\u00e8res qui coupent anatomiquement le flux sanguin veineux sont r\u00e9pertori\u00e9es dans la section suivante\u00a0:<\/p>\n<ul>\n<li>\n<h4><strong>Mai \u2013 Syndrome de Thurner\u00a0:<\/strong><\/h4>\n<\/li>\n<\/ul>\n<p>C&#8217;est la compression de l&#8217;art\u00e8re iliaque commune droite sur la veine iliaque commune gauche.<\/p>\n<ul>\n<li>\n<h4><strong>R\u00e9tro \u2013 Veine R\u00e9nale Gauche Aortique\u00a0:<\/strong><\/h4>\n<\/li>\n<\/ul>\n<p>C&#8217;est la condition o\u00f9 la veine r\u00e9nale gauche est situ\u00e9e derri\u00e8re l&#8217;aorte et la veine ovarienne gauche est expos\u00e9e \u00e0 la pression.<\/p>\n<ul>\n<li>\n<h4><strong>Syndrome Casse-Noisette\u00a0:<\/strong><\/h4>\n<\/li>\n<\/ul>\n<p>C&#8217;est une condition dans laquelle l&#8217;ovaire gauche et la veine r\u00e9nale gauche sont comprim\u00e9es par l&#8217;art\u00e8re m\u00e9sent\u00e9rique sup\u00e9rieure.<\/p>\n<h2><strong>M\u00e9thodes De Diagnostic Du Syndrome De Congestion Pelvienne<\/strong><\/h2>\n<h3><strong>Quelles Sont Les Plaintes Des Patients Atteints Du Syndrome De Congestion Pelvienne\u00a0?<\/strong><\/h3>\n<ul>\n<li>Douleur pelvienne : Elle est fr\u00e9quente et dure plus de 6 mois. Elle s&#8217;aggrave chez la plupart des patients, en particulier lorsqu&#8217;ils sont debout et assis. La douleur survient avant ou pendant les menstruations \u00e0 un rythme substantiel. Cependant, pendant ou imm\u00e9diatement apr\u00e8s les rapports sexuels, le patient peut ressentir des douleurs qui le g\u00eanent beaucoup.<\/li>\n<li>Formation de varices dans la r\u00e9gion de l&#8217;aine<\/li>\n<li>Urination fr\u00e9quente<\/li>\n<li>&#8220;Dysm\u00e9norrh\u00e9e&#8221;, c&#8217;est-\u00e0-dire la p\u00e9riode menstruelle douloureuse<\/li>\n<li>Formation d&#8217;h\u00e9morro\u00efdes (h\u00e9morro\u00efdes) dans la r\u00e9gion du si\u00e8ge<\/li>\n<li>\u00c9coulement se produisant dans la r\u00e9gion du vagin<\/li>\n<li>Douleur autour de la taille<\/li>\n<li>La D\u00e9pression<\/li>\n<li>Fatigue<\/li>\n<li>Formation de varices dans la r\u00e9gion de la vulve\/du vagin<\/li>\n<li>G\u00eane dans la r\u00e9gion du si\u00e8ge<\/li>\n<li>Sensibilit\u00e9 dans la r\u00e9gion de l&#8217;abdomen ou du bassin<\/li>\n<li>Gonflement et pl\u00e9nitude dans la r\u00e9gion de la vulve<\/li>\n<\/ul>\n<h3><strong>Comment Diagnostique-T-On Le <a href=\"https:\/\/www.plasticsurgeryistanbul.net\/fr\/\" target=\"_blank\" rel=\"noopener\">Syndrome De Congestion Pelvienne<\/a> ?<\/strong><\/h3>\n<p>Le diagnostic du syndrome de congestion pelvienne est encore assez difficile, m\u00eame s&#8217;il est dans une position plus courte et plus facile par rapport aux temps pass\u00e9s.<\/p>\n<p>Cependant, le diagnostic du syndrome peut \u00eatre pos\u00e9 plus pr\u00e9cocement chez les patients pr\u00e9sentant une vasodilatation variqueuse tr\u00e8s importante de la vulve ou du vagin.<\/p>\n<p>En plus de cette condition, plus de la moiti\u00e9 des patients atteints du syndrome de congestion pelvienne ont des kystes ovariens.<\/p>\n<p>Cependant, bien que la raison de ce lien entre le syndrome de congestion pelvienne et la formation de kystes ovariens ne puisse pas \u00eatre enti\u00e8rement expliqu\u00e9e, on pense que le lien est d\u00fb \u00e0 une stimulation excessive de l&#8217;hormone \u0153strog\u00e8ne.<\/p>\n<h4><strong>Examen \u00c9chographique Pelvien\u00a0:<\/strong><\/h4>\n<p>Cet examen peut \u00eatre fait \u00e0 la fois &#8220;transabdominal&#8221;, c&#8217;est-\u00e0-dire &#8220;par l&#8217;abdomen&#8221; et &#8220;transvaginal&#8221;, c&#8217;est-\u00e0-dire &#8220;par le vagin&#8221;. La contribution de &#8220;l&#8217;examen \u00e9chographique Doppler&#8221; \u00e0 l&#8217;examen d\u00e9taill\u00e9 du flux sanguin veineux dans la r\u00e9gion pelvienne est assez importante.<\/p>\n<h4><strong>Tomodensitom\u00e9trie Pelvienne (CT) Ou \u0130magerie Par R\u00e9sonance Magn\u00e9tique (RM) :<\/strong><\/h4>\n<p>Ces m\u00e9thodes sont d&#8217;une importance cruciale pour la d\u00e9monstration d\u00e9taill\u00e9e et l&#8217;examen des varices de la r\u00e9gion pelvienne.<\/p>\n<p>La tomodensitom\u00e9trie et l&#8217;IRM fournissent des informations sur les structures vasculaires et r\u00e9v\u00e8lent leurs connexions avec d&#8217;autres structures anatomiques pelviennes, en particulier &#8220;ovaires et ut\u00e9rus&#8221;.<\/p>\n<p>L&#8217;imagerie par r\u00e9sonance magn\u00e9tique avec colorant de contraste est une m\u00e9thode sup\u00e9rieure par rapport \u00e0 l&#8217;examen tomodensitom\u00e9trique car elle n&#8217;\u00e9met pas de rayonnement pendant l&#8217;examen.<\/p>\n<h4><strong>Phl\u00e9bographie Diagnostique\u00a0:<\/strong><\/h4>\n<p>Afin d&#8217;effectuer un examen veinographique, des appareils d&#8217;imagerie utilis\u00e9s dans le service d&#8217;angiographie sont n\u00e9cessaires. G\u00e9n\u00e9ralement, la veine inguinale droite est utilis\u00e9e pour effectuer cette proc\u00e9dure.<\/p>\n<p>\u00c0 l&#8217;aide d&#8217;un fil et d&#8217;un cath\u00e9ter (tube en plastique) positionn\u00e9s dans la veine inguinale, les veines ovariennes gauche et droite sont examin\u00e9es s\u00e9par\u00e9ment.<\/p>\n<p>De cette mani\u00e8re, les diam\u00e8tres des veines et les directions du flux sanguin dans celles-ci sont d\u00e9termin\u00e9s.<\/p>\n<h4><strong>Examen Laparoscopique\u00a0:<\/strong><\/h4>\n<p>Cet examen doit \u00eatre appliqu\u00e9 en particulier pour les patients souffrant de douleurs pelviennes chroniques s\u00e9v\u00e8res.<\/p>\n<p>Examen laparoscopique\u00a0; Chez 80% \u00e0 90% des patients pr\u00e9sentant une hypertrophie variqueuse pelvienne, la m\u00e9thode n&#8217;est pas b\u00e9n\u00e9fique car la m\u00e9thode est r\u00e9alis\u00e9e en position allong\u00e9e et du dioxyde de carbone est inject\u00e9 dans l&#8217;abdomen lors de l&#8217;application.<\/p>\n<p>Parce que cet examen provoque un r\u00e9tr\u00e9cissement des \u00e9largissements variqueux.<\/p>\n<h3><strong>Quel Est Le Traitement Du Syndrome De Congestion Pelvienne ?<\/strong><\/h3>\n<p>Les m\u00e9dicaments peuvent \u00eatre essay\u00e9s chez les patients \u00e0 un stade pr\u00e9coce. Certains m\u00e9dicaments qui pr\u00e9viendront la vasodilatation et r\u00e9tabliront l&#8217;\u00e9quilibre hormonal peuvent r\u00e9duire le taux de progression de la maladie et parfois arr\u00eater la progression.<\/p>\n<p>Cependant, divers analg\u00e9siques peuvent \u00eatre utilis\u00e9s pour soulager les douleurs pelviennes. Cependant, la technique la plus importante dans le traitement d\u00e9finitif de la maladie est l&#8217;embolisation des veines pelviennes probl\u00e9matiques, c&#8217;est-\u00e0-dire leur fermeture, au moyen d&#8217;un cath\u00e9ter.<\/p>\n<p>Dans ces proc\u00e9dures r\u00e9alis\u00e9es par la veine inguinale ou du cou, des veines \u00e9largies et structurellement alt\u00e9r\u00e9es dans la r\u00e9gion pelvienne sont d\u00e9tect\u00e9es. Ces vaisseaux probl\u00e9matiques sont ferm\u00e9s avec un \u00e9quipement sp\u00e9cial (spirale, mousse, m\u00e9dicaments scl\u00e9rosants, etc.).<\/p>\n<p>Le succ\u00e8s technique de la proc\u00e9dure d&#8217;embolisation veineuse pelvienne est de 99 % et le taux de r\u00e9cidive est inf\u00e9rieur \u00e0 10 %.<\/p>\n<p>Les proc\u00e9dures peuvent \u00eatre effectu\u00e9es \u00e0 n&#8217;importe quelle saison de l&#8217;ann\u00e9e, et les patients peuvent \u00eatre lib\u00e9r\u00e9s le m\u00eame jour et reprendre leur travail et leur vie sociale le lendemain.<\/p>\n<p>Le moment de la proc\u00e9dure n&#8217;a rien \u00e0 voir avec la p\u00e9riode menstruelle. Il n&#8217;y a aucun changement dans la fertilit\u00e9 et le cycle menstruel apr\u00e8s la proc\u00e9dure.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires) Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieure du tronc. Cette maladie, \u00e9galement traduite par syndrome d&#8217;obstruction pelvienne, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7644,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1467],"tags":[1690,1689],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.5 (Yoast SEO v18.4.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu&#039;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires - Turkey Istanbul Medical<\/title>\n<meta name=\"description\" content=\"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires\" \/>\n<meta property=\"og:description\" content=\"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Turkey Istanbul Medical\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-11T09:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-01T12:50:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1074\" \/>\n\t<meta property=\"og:image:height\" content=\"965\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Turkey Istanbul Medical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#organization\",\"name\":\"Turkey Istanbul Medical\",\"url\":\"https:\/\/turkeyistanbulmedical.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2021\/04\/cropped-TIM-1-1-1.png\",\"contentUrl\":\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2021\/04\/cropped-TIM-1-1-1.png\",\"width\":394,\"height\":324,\"caption\":\"Turkey Istanbul Medical\"},\"image\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#website\",\"url\":\"https:\/\/turkeyistanbulmedical.com\/\",\"name\":\"Turkey Istanbul Medical\",\"description\":\"Healthcare consulting - Best Doctors and Hospital Istanbul\",\"publisher\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turkeyistanbulmedical.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg\",\"contentUrl\":\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg\",\"width\":1074,\"height\":965,\"caption\":\"Pelvic Congestion Syndrome\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage\",\"url\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/\",\"name\":\"Qu'est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires - Turkey Istanbul Medical\",\"isPartOf\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage\"},\"datePublished\":\"2022-07-11T09:40:42+00:00\",\"dateModified\":\"2022-10-01T12:50:58+00:00\",\"description\":\"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu\",\"breadcrumb\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/turkeyistanbulmedical.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#\/schema\/person\/00086cb50936bc11058a287837928bbc\"},\"headline\":\"Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires\",\"datePublished\":\"2022-07-11T09:40:42+00:00\",\"dateModified\":\"2022-10-01T12:50:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage\"},\"wordCount\":1784,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg\",\"keywords\":[\"Syndrome De Congestion Pelvienne\",\"Syndrome De Congestion Veineuse Pelvienne\"],\"articleSection\":[\"Gyn\u00e9cologie et Obst\u00e9trique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#\/schema\/person\/00086cb50936bc11058a287837928bbc\",\"name\":\"Turkey Istanbul Medical\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turkeyistanbulmedical.com\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/73777217e21bf71b3a3405be6e3ab19a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/73777217e21bf71b3a3405be6e3ab19a?s=96&d=mm&r=g\",\"caption\":\"Turkey Istanbul Medical\"},\"sameAs\":[\"https:\/\/turkeyistanbulmedical.com\"],\"url\":\"https:\/\/turkeyistanbulmedical.com\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qu'est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires - Turkey Istanbul Medical","description":"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu'est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires","og_description":"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu","og_url":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/","og_site_name":"Turkey Istanbul Medical","article_published_time":"2022-07-11T09:40:42+00:00","article_modified_time":"2022-10-01T12:50:58+00:00","og_image":[{"width":1074,"height":965,"url":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Turkey Istanbul Medical","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/turkeyistanbulmedical.com\/#organization","name":"Turkey Istanbul Medical","url":"https:\/\/turkeyistanbulmedical.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/turkeyistanbulmedical.com\/#logo","inLanguage":"fr-FR","url":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2021\/04\/cropped-TIM-1-1-1.png","contentUrl":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2021\/04\/cropped-TIM-1-1-1.png","width":394,"height":324,"caption":"Turkey Istanbul Medical"},"image":{"@id":"https:\/\/turkeyistanbulmedical.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/turkeyistanbulmedical.com\/#website","url":"https:\/\/turkeyistanbulmedical.com\/","name":"Turkey Istanbul Medical","description":"Healthcare consulting - Best Doctors and Hospital Istanbul","publisher":{"@id":"https:\/\/turkeyistanbulmedical.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turkeyistanbulmedical.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg","contentUrl":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg","width":1074,"height":965,"caption":"Pelvic Congestion Syndrome"},{"@type":"WebPage","@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage","url":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/","name":"Qu'est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires - Turkey Istanbul Medical","isPartOf":{"@id":"https:\/\/turkeyistanbulmedical.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage"},"datePublished":"2022-07-11T09:40:42+00:00","dateModified":"2022-10-01T12:50:58+00:00","description":"Le syndrome de congestion\u00a0 veineuse pelvienne est une maladie chronique qui se manifeste par des douleurs prolong\u00e9es dans la partie inf\u00e9rieu","breadcrumb":{"@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/turkeyistanbulmedical.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires"}]},{"@type":"Article","@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#article","isPartOf":{"@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage"},"author":{"@id":"https:\/\/turkeyistanbulmedical.com\/#\/schema\/person\/00086cb50936bc11058a287837928bbc"},"headline":"Qu&#8217;est-Ce Que Le Syndrome De Congestion Veineuse Pelvienne ? (\u00c9checs Observ\u00e9s Dans Les Veines Ovariennes\/Testiculaires","datePublished":"2022-07-11T09:40:42+00:00","dateModified":"2022-10-01T12:50:58+00:00","mainEntityOfPage":{"@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#webpage"},"wordCount":1784,"commentCount":0,"publisher":{"@id":"https:\/\/turkeyistanbulmedical.com\/#organization"},"image":{"@id":"https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#primaryimage"},"thumbnailUrl":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg","keywords":["Syndrome De Congestion Pelvienne","Syndrome De Congestion Veineuse Pelvienne"],"articleSection":["Gyn\u00e9cologie et Obst\u00e9trique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/turkeyistanbulmedical.com\/fr\/quest-ce-que-le-syndrome-de-congestion-veineuse-pelvienne-echecs-observes-dans-les-veines-ovariennes-testiculaires\/#respond"]}]},{"@type":"Person","@id":"https:\/\/turkeyistanbulmedical.com\/#\/schema\/person\/00086cb50936bc11058a287837928bbc","name":"Turkey Istanbul Medical","image":{"@type":"ImageObject","@id":"https:\/\/turkeyistanbulmedical.com\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/73777217e21bf71b3a3405be6e3ab19a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73777217e21bf71b3a3405be6e3ab19a?s=96&d=mm&r=g","caption":"Turkey Istanbul Medical"},"sameAs":["https:\/\/turkeyistanbulmedical.com"],"url":"https:\/\/turkeyistanbulmedical.com\/fr\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/turkeyistanbulmedical.com\/wp-content\/uploads\/2022\/07\/Pelvic-Congestion-Syndrome.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/posts\/7652"}],"collection":[{"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/comments?post=7652"}],"version-history":[{"count":1,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/posts\/7652\/revisions"}],"predecessor-version":[{"id":7653,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/posts\/7652\/revisions\/7653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/media\/7644"}],"wp:attachment":[{"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/media?parent=7652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/categories?post=7652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turkeyistanbulmedical.com\/fr\/wp-json\/wp\/v2\/tags?post=7652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}